{"id":2479,"date":"2018-01-31T11:14:31","date_gmt":"2018-01-31T11:14:31","guid":{"rendered":"http:\/\/eurosigno.com\/?page_id=2479"},"modified":"2018-05-30T13:55:46","modified_gmt":"2018-05-30T13:55:46","slug":"registro-patentes-modelos-espanoles","status":"publish","type":"page","link":"https:\/\/eurosigno.com\/en\/registro-patentes\/registro-patentes-modelos-espanoles\/","title":{"rendered":"Registro patentes y modelos espa\u00f1oles"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid vc_custom_1508938086653\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><h1 id=\"uvc-type-wrap-7582\"  data-ultimate-target='#uvc-type-wrap-7582'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}'  class=\"uvc-type-wrap  ult-adjust-bottom-margin ult-responsive titular uvc-type-align-left uvc-type-no-prefix uvc-wrap-39653142296a9843379ed5f\" style=\"text-align:left;\"><span id=\"typed-39653142296a9843379ed5f\" class=\"ultimate-typed-main\" style=\"color:#6780be; font-family:&#039;Playfair Display&#039;;font-weight:normal; text-transform: unset;\"><\/span><script type=\"text\/javascript\"> \n\t\t\t\t\t\tjQuery(function($){ \n\t\t\t\t\t\t\t$(document).ready(function(){\n\t\t\t\t\t\t\t\tif( typeof jQuery(\"#typed-39653142296a9843379ed5f\").typed == \"function\"){\n\t\t\t\t\t\t\t\t\t$(\"#typed-39653142296a9843379ed5f\").typed({\n\t\t\t\t\t\t\t\t\t\tstrings: [\"Registro de patentes y modelos espa\u00f1oles\"],\n\t\t\t\t\t\t\t\t\t\ttypeSpeed: 50,\n\t\t\t\t\t\t\t\t\t\tbackSpeed: 0,\n\t\t\t\t\t\t\t\t\t\tstartDelay: 200,\n\t\t\t\t\t\t\t\t\t\tbackDelay: 1500,\n\t\t\t\t\t\t\t\t\t\tloop: false,\n\t\t\t\t\t\t\t\t\t\tloopCount: false,\n\t\t\t\t\t\t\t\t\t\tshowCursor: false,\n\t\t\t\t\t\t\t\t\t\tcursorChar: \"|\",\n\t\t\t\t\t\t\t\t\t\tattr: null\n\t\t\t\t\t\t\t\t\t});\n\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t});\n\t\t\t\t\t\t});\n\t\t\t\t\t<\/script><\/h1><\/div><\/div><\/div><\/div><!-- Row Backgrounds --><div class=\"upb_color\" data-bg-override=\"full\" data-bg-color=\"#f8f8f9\" data-fadeout=\"\" data-fadeout-percentage=\"30\" data-parallax-content=\"\" data-parallax-content-sense=\"30\" data-row-effect-mobile-disable=\"true\" data-img-parallax-mobile-disable=\"true\" data-rtl=\"false\"  data-custom-vc-row=\"\"  data-vc=\"6.9.0\"  data-is_old_vc=\"\"  data-theme-support=\"\"   data-overlay=\"false\" data-overlay-color=\"\" data-overlay-pattern=\"\" data-overlay-pattern-opacity=\"\" data-overlay-pattern-size=\"\"    ><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid migas\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<span><span><a href=\"https:\/\/eurosigno.com\/en\/\">Home<\/a><\/span><\/span>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div class=\"vc_row wpb_row vc_row-fluid dt-default\" style=\"margin-top: 0px;margin-bottom: 0px\"><div class=\"wpb_column vc_column_container vc_col-sm-9\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img width=\"1200\" height=\"544\" src=\"https:\/\/eurosigno.com\/wp-content\/uploads\/2018\/01\/registrar-patente-espana.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"Registrar Patente espa\u00f1ola\" loading=\"lazy\" title=\"Registrar Patente espa\u00f1ola\" srcset=\"https:\/\/eurosigno.com\/wp-content\/uploads\/2018\/01\/registrar-patente-espana.jpg 1200w, https:\/\/eurosigno.com\/wp-content\/uploads\/2018\/01\/registrar-patente-espana-300x136.jpg 300w, https:\/\/eurosigno.com\/wp-content\/uploads\/2018\/01\/registrar-patente-espana-768x348.jpg 768w, https:\/\/eurosigno.com\/wp-content\/uploads\/2018\/01\/registrar-patente-espana-1024x464.jpg 1024w\" sizes=\"(max-width: 1200px) 100vw, 1200px\"  data-dt-location=\"https:\/\/eurosigno.com\/en\/registro-patentes\/registro-patentes-modelos-espanoles\/registrar-patente-espana\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div id=\"ultimate-heading-54096a984337a4a7d\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-54096a984337a4a7d uvc-7240\" data-hspacer=\"no_spacer\"  data-halign=\"left\" style=\"text-align:left\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-sub-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-54096a984337a4a7d .uvc-sub-heading '  data-responsive-json-new='{\"font-size\":\"desktop:25px;\",\"line-height\":\"desktop:54px;\"}'  style=\"font-family:&#039;Playfair Display&#039;;font-weight:normal;color:#6b80b9;margin-bottom:10px;\">Asesoramiento y orientaci\u00f3n en el registro de patentes y modelos de utilidad espa\u00f1oles<\/div><\/div><div class=\"ult-spacer spacer-6a984337a4abc\" data-id=\"6a984337a4abc\" data-height=\"30\" data-height-mobile=\"30\" data-height-tab=\"30\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element  vc_custom_1527688532081\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Las <strong>patentes y modelos de utilidad espa\u00f1oles<\/strong> nos otorgan un derecho de explotaci\u00f3n exclusivo y excluyente en todo el territorio nacional. La\u00a0<a href=\"https:\/\/www.oepm.es\/\" target=\"_blank\" rel=\"noopener\">Oficina Espa\u00f1ola de Patentes y Marcas (O.E.P.M.)<\/a> es el organismo encargado del <strong>registro de las patentes y modelos de utilidad en Espa\u00f1a.<\/strong><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element  vc_custom_1527688543676\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2><span style=\"color: #6780be;\">Alto nivel de exigencia por parte de la OEPM<\/span><\/h2>\n<p>El nombramiento por parte de la <strong>Organizaci\u00f3n Mundial de la Propiedad Industrial de la OEPM<\/strong> como <strong>Administraci\u00f3n de B\u00fasqueda Internacional (1993)<\/strong> y como <strong>Administraci\u00f3n de Examen Preliminar (2003)<\/strong> y la entrada en vigor de la nueva <a href=\"http:\/\/www.oepm.es\/export\/sites\/oepm\/comun\/documentos_relacionados\/Publicaciones\/monografias\/Ley_de_Patentes_24_julio_2015.pdf\" target=\"_blank\" rel=\"noopener\">Ley 24\/2015, de 24 de junio, de Patentes<\/a>, el uno de abril de 2017, en la que se introdujo la obligatoriedad de superar un examen de fondo de los requisitos de patentabilidad, han situado a la OEPM al nivel de las Oficinas de Patentes m\u00e1s exigentes del mundo.<\/p>\n<p>Para vencer con \u00e9xito ese alto nivel de exigencia, es fundamental contar con asesoramiento profesional. En EUROSIGNO le orientamos y ayudamos para que su patente y\/o modelo de utilidad logren un resultado favorable.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"Bloque-form-lateral wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid form-lateral2 vc_custom_1517392895096 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element  vc_custom_1525774902792\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center; font-family: 'Open Sans';\">\u00bfQuieres registrar una patente en Espa\u00f1a?<\/p>\n<p style=\"text-align: center; font-family: 'Open Sans';\"><strong>ASK US ABOUT YOUR CASE<\/strong><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_icon_element vc_icon_element-outer vc_icon_element-align-center\"><div class=\"vc_icon_element-inner vc_icon_element-color-blue vc_icon_element-size-md vc_icon_element-style- vc_icon_element-background-color-grey\" ><span class=\"vc_icon_element-icon fa fa-envelope-open-o\" ><\/span><\/div><\/div><div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f2086-o1\" lang=\"es-ES\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/2479#wpcf7-f2086-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/en\/wp-json\/wp\/v2\/pages\/2479#wpcf7-f2086-o1\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"2086\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.6.4\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f2086-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<div class=\"form-lateral\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name (required)\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email (required)\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tel-841\"><input type=\"tel\" name=\"tel-841\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-required wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone (required)\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input type=\"text\" name=\"your-subject\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Subject\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"5\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Message\"><\/textarea><\/span><\/p>\n<div class=\"terms\"><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-831\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"acceptance-831\" value=\"1\" aria-invalid=\"false\" \/><\/span><\/span><\/span><span style=\"font-size:14px; color: #9e9fa2; font-family: 'Open Sans';\"> I accept the <\/span><a href=\"https:\/\/eurosigno.com\/en\/aviso-legal\/\" style=\"font-size:14px; color: #9e9fa2;text-decoration:none; font-family: 'Open Sans';\" target=\"_blank\">legal terms and the privacy policy<\/a><\/div>\n<p><input type=\"submit\" value=\"Send\" class=\"wpcf7-form-control has-spinner wpcf7-submit\" \/>\n<\/p><\/div>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><section class=\"vc_section\"><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" data-vc-stretch-content=\"true\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1517390167662 vc_row-no-padding vc_row-o-equal-height vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"ult-spacer spacer-6a984337a7890\" data-id=\"6a984337a7890\" data-height=\"70\" data-height-mobile=\"20\" data-height-tab=\"70\" data-height-tab-portrait=\"30\" data-height-mobile-landscape=\"20\" style=\"clear:both;display:block;\"><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1516275555453\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div id=\"ultimate-heading-51196a984337a7f6a\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-51196a984337a7f6a uvc-4355  uvc-heading-default-font-sizes\" data-hspacer=\"no_spacer\"  data-halign=\"center\" style=\"text-align:center\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-sub-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-51196a984337a7f6a .uvc-sub-heading '  data-responsive-json-new='{\"font-size\":\"desktop:22px;\",\"line-height\":\"\"}'  style=\"font-family:&#039;Playfair Display&#039;;font-weight:600;color:#ffffff;\"><\/p>\n<p style=\"text-align: center; font-weight: 300 !important;\">En EUROSIGNO tenemos amplia experiencia y \u00e9xitos en registro de patentes y modelos de utilidad en Espa\u00f1a<\/p>\n<p><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><div class=\"vc_empty_space\"   style=\"height: 25px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"ult-spacer spacer-6a984337a8590\" data-id=\"6a984337a8590\" data-height=\"70\" data-height-mobile=\"20\" data-height-tab=\"70\" data-height-tab-portrait=\"30\" data-height-mobile-landscape=\"20\" style=\"clear:both;display:block;\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><!-- Row Backgrounds --><div class=\"upb_bg_img\" data-ultimate-bg=\"url(https:\/\/eurosigno.com\/wp-content\/uploads\/2018\/01\/eurosigno-patente.jpg)\" data-image-id=\"id^2420|url^http:\/\/eurosigno.com\/wp-content\/uploads\/2018\/01\/eurosigno-patente.jpg|caption^null|alt^Registro de Patentes con Eurosigno|title^eurosigno-patente|description^null\" data-ultimate-bg-style=\"vcpb-vz-jquery\" data-bg-img-repeat=\"no-repeat\" data-bg-img-size=\"cover\" data-bg-img-position=\"\" data-parallx_sense=\"30\" data-bg-override=\"full\" data-bg_img_attach=\"scroll\" data-upb-overlay-color=\"rgba(103,150,191,0.2)\" data-upb-bg-animation=\"\" data-fadeout=\"\" data-bg-animation=\"left-animation\" data-bg-animation-type=\"h\" data-animation-repeat=\"repeat\" data-fadeout-percentage=\"30\" data-parallax-content=\"parallax_content_value\" data-parallax-content-sense=\"30\" data-row-effect-mobile-disable=\"true\" data-img-parallax-mobile-disable=\"true\" data-rtl=\"false\"  data-custom-vc-row=\"\"  data-vc=\"6.9.0\"  data-is_old_vc=\"\"  data-theme-support=\"\"   data-overlay=\"true\" data-overlay-color=\"rgba(103,150,191,0.2)\" data-overlay-pattern=\"https:\/\/eurosigno.com\/wp-content\/plugins\/Ultimate_VC_Addons\/assets\/images\/patterns\/01.png\" data-overlay-pattern-opacity=\"0.95\" data-overlay-pattern-size=\"\" data-overlay-pattern-attachment=\"scroll\"    ><\/div><\/section><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid servicios-ampliacion\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner vc_custom_1521632670328\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"titulo3\">\n<div style=\"float: left;\">\n<h2 style=\"font-family: 'Playfair Display'; font-weight: normal; color: #fff; font-size: 25px;\">SERVICES<\/h2>\n<\/div>\n<div style=\"float: left;\"><img class=\"titular2-barra\" src=\"\/wp-content\/uploads\/2018\/01\/separador-blanco-1.png\" \/><\/div>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"ult-spacer spacer-6a984337a9667\" data-id=\"6a984337a9667\" data-height=\"80\" data-height-mobile=\"60\" data-height-tab=\"60\" data-height-tab-portrait=\"60\" data-height-mobile-landscape=\"60\" style=\"clear:both;display:block;\"><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"aio-icon-component    style_1\"><a class=\"aio-icon-box-link\" href=\"\/en\/asesoramiento\/\" ><div id=\"Info-box-wrap-9216\" class=\"aio-icon-box default-icon\" style=\"\"  ><div class=\"aio-icon-default\"><div class=\"ult-just-icon-wrapper\"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img\" style=\"font-size:65px;display:inline-block;\" >\n\t<img class=\"img-icon\" alt=\"icono-servicios1\" src=\"https:\/\/eurosigno.com\/wp-content\/uploads\/2018\/01\/icono-servicios1.png\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-9216 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"desktop:17px;\",\"line-height\":\"\"}'  style=\"font-family:&#039;Open Sans&#039;;font-weight:600;color:#ffffff;\">Advice on protection<\/h3><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/a><\/div> <!-- aio-icon-component --><div class=\"aio-icon-component    style_1\"><a class=\"aio-icon-box-link\" href=\"\/en\/informes\/\" ><div id=\"Info-box-wrap-1329\" class=\"aio-icon-box default-icon\" style=\"\"  ><div class=\"aio-icon-default\"><div class=\"ult-just-icon-wrapper\"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img\" style=\"font-size:65px;display:inline-block;\" >\n\t<img class=\"img-icon\" alt=\"servicios-icono6\" src=\"https:\/\/eurosigno.com\/wp-content\/uploads\/2018\/01\/servicios-icono6.png\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-1329 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"desktop:17px;\",\"line-height\":\"\"}'  style=\"font-family:&#039;Open Sans&#039;;font-weight:600;color:#ffffff;\">Search for previous reports<\/h3><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/a><\/div> <!-- aio-icon-component --><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"aio-icon-component    style_1\"><a class=\"aio-icon-box-link\" href=\"\/en\/contratos\/\" ><div id=\"Info-box-wrap-1046\" class=\"aio-icon-box default-icon\" style=\"\"  ><div class=\"aio-icon-default\"><div class=\"ult-just-icon-wrapper\"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img\" style=\"font-size:65px;display:inline-block;\" >\n\t<img class=\"img-icon\" alt=\"icono-servicios2\" src=\"https:\/\/eurosigno.com\/wp-content\/uploads\/2018\/01\/icono-servicios2.png\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-1046 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"desktop:17px;\",\"line-height\":\"\"}'  style=\"font-family:&#039;Open Sans&#039;;font-weight:600;color:#ffffff;\">Contracts<\/h3><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/a><\/div> <!-- aio-icon-component --><div class=\"aio-icon-component    style_1\"><a class=\"aio-icon-box-link\" href=\"\/en\/registro\/\" ><div id=\"Info-box-wrap-4957\" class=\"aio-icon-box default-icon\" style=\"\"  ><div class=\"aio-icon-default\"><div class=\"ult-just-icon-wrapper\"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img\" style=\"font-size:65px;display:inline-block;\" >\n\t<img class=\"img-icon\" alt=\"servicios-icono4\" src=\"https:\/\/eurosigno.com\/wp-content\/uploads\/2018\/01\/servicios-icono4.png\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-4957 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"desktop:17px;\",\"line-height\":\"\"}'  style=\"font-family:&#039;Open Sans&#039;;font-weight:600;color:#ffffff;\">Registration - procedures<\/h3><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/a><\/div> <!-- aio-icon-component --><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"aio-icon-component    style_1\"><a class=\"aio-icon-box-link\" href=\"\/en\/defensa-juridica\/\" ><div id=\"Info-box-wrap-7489\" class=\"aio-icon-box default-icon\" style=\"\"  ><div class=\"aio-icon-default\"><div class=\"ult-just-icon-wrapper\"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img\" style=\"font-size:65px;display:inline-block;\" >\n\t<img class=\"img-icon\" alt=\"null\" src=\"https:\/\/eurosigno.com\/wp-content\/uploads\/2018\/01\/icono-servicios5.png\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-7489 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"desktop:17px;\",\"line-height\":\"\"}'  style=\"font-family:&#039;Open Sans&#039;;font-weight:600;color:#ffffff;\">Legal defence<\/h3><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/a><\/div> <!-- aio-icon-component --><div class=\"aio-icon-component    style_1\"><a class=\"aio-icon-box-link\" href=\"\/en\/vigilancia\/\" ><div id=\"Info-box-wrap-8729\" class=\"aio-icon-box default-icon\" style=\"\"  ><div class=\"aio-icon-default\"><div class=\"ult-just-icon-wrapper\"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img\" style=\"font-size:65px;display:inline-block;\" >\n\t<img class=\"img-icon\" alt=\"null\" src=\"https:\/\/eurosigno.com\/wp-content\/uploads\/2018\/01\/servicios-icono3.png\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-8729 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"desktop:17px;\",\"line-height\":\"\"}'  style=\"font-family:&#039;Open Sans&#039;;font-weight:600;color:#ffffff;\">Monitoring<\/h3><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/a><\/div> <!-- aio-icon-component --><\/div><\/div><\/div><\/div><div class=\"ult-spacer spacer-6a984337ab354\" data-id=\"6a984337ab354\" data-height=\"20\" data-height-mobile=\"20\" data-height-tab=\"20\" data-height-tab-portrait=\"20\" data-height-mobile-landscape=\"20\" style=\"clear:both;display:block;\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><!-- Row Backgrounds --><div class=\"upb_bg_img\" data-ultimate-bg=\"url(https:\/\/eurosigno.com\/wp-content\/uploads\/2016\/02\/eursigno-nosotros-bg.jpg)\" data-image-id=\"id^1886|url^http:\/\/eurosigno.com\/wp-content\/uploads\/2016\/02\/eursigno-nosotros-bg.jpg|caption^null|alt^eurosigno-nosotros-bg|title^eurosigno-nosotros-bg|description^null\" data-ultimate-bg-style=\"vcpb-default\" data-bg-img-repeat=\"no-repeat\" data-bg-img-size=\"cover\" data-bg-img-position=\"\" data-parallx_sense=\"30\" data-bg-override=\"0\" data-bg_img_attach=\"scroll\" data-upb-overlay-color=\"\" data-upb-bg-animation=\"\" data-fadeout=\"\" data-bg-animation=\"left-animation\" data-bg-animation-type=\"h\" data-animation-repeat=\"repeat\" data-fadeout-percentage=\"30\" data-parallax-content=\"\" data-parallax-content-sense=\"30\" data-row-effect-mobile-disable=\"true\" data-img-parallax-mobile-disable=\"true\" data-rtl=\"false\"  data-custom-vc-row=\"\"  data-vc=\"6.9.0\"  data-is_old_vc=\"\"  data-theme-support=\"\"   data-overlay=\"false\" data-overlay-color=\"\" data-overlay-pattern=\"\" data-overlay-pattern-opacity=\"\" data-overlay-pattern-size=\"\"    ><\/div>","protected":false},"excerpt":{"rendered":"<p>Home Asesoramiento y orientaci\u00f3n en el registro de patentes y modelos de utilidad espa\u00f1oles Las patentes y modelos de utilidad espa\u00f1oles nos otorgan un derecho de explotaci\u00f3n exclusivo y excluyente en todo el territorio nacional. La\u00a0Oficina Espa\u00f1ola de Patentes y Marcas (O.E.P.M.) es el organismo encargado del registro de las patentes y modelos de utilidad&hellip;<\/p>","protected":false},"author":2,"featured_media":0,"parent":2122,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"categories":[],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Registro de patentes y modelos de utilidad espa\u00f1oles | EUROSIGNO<\/title>\n<meta name=\"description\" content=\"El registro de patentes y modelos de utilidad espa\u00f1oles nos otorgan un derecho de explotaci\u00f3n exclusivo y excluyente en todo el territorio nacional.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eurosigno.com\/en\/registro-patentes\/registro-patentes-modelos-espanoles\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Registro de patentes y modelos de utilidad espa\u00f1oles | EUROSIGNO\" \/>\n<meta property=\"og:description\" content=\"El registro de patentes y modelos de utilidad espa\u00f1oles nos otorgan un derecho de explotaci\u00f3n exclusivo y excluyente en todo el territorio nacional.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eurosigno.com\/en\/registro-patentes\/registro-patentes-modelos-espanoles\/\" \/>\n<meta property=\"og:site_name\" content=\"Eurosigno Patentes y Marcas, S.L.\" \/>\n<meta property=\"article:modified_time\" content=\"2018-05-30T13:55:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eurosigno.com\/registro-patentes\/registro-patentes-modelos-espanoles\/\",\"url\":\"https:\/\/eurosigno.com\/registro-patentes\/registro-patentes-modelos-espanoles\/\",\"name\":\"Registro de patentes y modelos de utilidad espa\u00f1oles | EUROSIGNO\",\"isPartOf\":{\"@id\":\"https:\/\/eurosigno.com\/#website\"},\"datePublished\":\"2018-01-31T11:14:31+00:00\",\"dateModified\":\"2018-05-30T13:55:46+00:00\",\"description\":\"El registro de patentes y modelos de utilidad espa\u00f1oles nos otorgan un derecho de explotaci\u00f3n exclusivo y excluyente en todo el territorio nacional.\",\"breadcrumb\":{\"@id\":\"https:\/\/eurosigno.com\/registro-patentes\/registro-patentes-modelos-espanoles\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eurosigno.com\/registro-patentes\/registro-patentes-modelos-espanoles\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eurosigno.com\/registro-patentes\/registro-patentes-modelos-espanoles\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/eurosigno.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Registro de patentes\",\"item\":\"https:\/\/eurosigno.com\/registro-patentes\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Registro patentes y modelos espa\u00f1oles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eurosigno.com\/#website\",\"url\":\"https:\/\/eurosigno.com\/\",\"name\":\"Eurosigno Patentes y Marcas, S.L.\",\"description\":\"Sitio web de Eurosigno S.L.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/eurosigno.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Registro de patentes y modelos de utilidad espa\u00f1oles | EUROSIGNO","description":"El registro de patentes y modelos de utilidad espa\u00f1oles nos otorgan un derecho de explotaci\u00f3n exclusivo y excluyente en todo el territorio nacional.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eurosigno.com\/en\/registro-patentes\/registro-patentes-modelos-espanoles\/","og_locale":"en_GB","og_type":"article","og_title":"Registro de patentes y modelos de utilidad espa\u00f1oles | EUROSIGNO","og_description":"El registro de patentes y modelos de utilidad espa\u00f1oles nos otorgan un derecho de explotaci\u00f3n exclusivo y excluyente en todo el territorio nacional.","og_url":"https:\/\/eurosigno.com\/en\/registro-patentes\/registro-patentes-modelos-espanoles\/","og_site_name":"Eurosigno Patentes y Marcas, S.L.","article_modified_time":"2018-05-30T13:55:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eurosigno.com\/registro-patentes\/registro-patentes-modelos-espanoles\/","url":"https:\/\/eurosigno.com\/registro-patentes\/registro-patentes-modelos-espanoles\/","name":"Registro de patentes y modelos de utilidad espa\u00f1oles | EUROSIGNO","isPartOf":{"@id":"https:\/\/eurosigno.com\/#website"},"datePublished":"2018-01-31T11:14:31+00:00","dateModified":"2018-05-30T13:55:46+00:00","description":"El registro de patentes y modelos de utilidad espa\u00f1oles nos otorgan un derecho de explotaci\u00f3n exclusivo y excluyente en todo el territorio nacional.","breadcrumb":{"@id":"https:\/\/eurosigno.com\/registro-patentes\/registro-patentes-modelos-espanoles\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eurosigno.com\/registro-patentes\/registro-patentes-modelos-espanoles\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/eurosigno.com\/registro-patentes\/registro-patentes-modelos-espanoles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eurosigno.com\/"},{"@type":"ListItem","position":2,"name":"Registro de patentes","item":"https:\/\/eurosigno.com\/registro-patentes\/"},{"@type":"ListItem","position":3,"name":"Registro patentes y modelos espa\u00f1oles"}]},{"@type":"WebSite","@id":"https:\/\/eurosigno.com\/#website","url":"https:\/\/eurosigno.com\/","name":"Eurosigno Patentes y Marcas, S.L.","description":"Sitio web de Eurosigno S.L.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eurosigno.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/eurosigno.com\/en\/wp-json\/wp\/v2\/pages\/2479"}],"collection":[{"href":"https:\/\/eurosigno.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/eurosigno.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/eurosigno.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/eurosigno.com\/en\/wp-json\/wp\/v2\/comments?post=2479"}],"version-history":[{"count":0,"href":"https:\/\/eurosigno.com\/en\/wp-json\/wp\/v2\/pages\/2479\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/eurosigno.com\/en\/wp-json\/wp\/v2\/pages\/2122"}],"wp:attachment":[{"href":"https:\/\/eurosigno.com\/en\/wp-json\/wp\/v2\/media?parent=2479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eurosigno.com\/en\/wp-json\/wp\/v2\/categories?post=2479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eurosigno.com\/en\/wp-json\/wp\/v2\/tags?post=2479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}